{"id":13828,"date":"2022-05-30T11:38:00","date_gmt":"2022-05-30T09:38:00","guid":{"rendered":"https:\/\/www.pilatre-de-rozier.com\/lmab\/?p=13828"},"modified":"2022-06-07T11:40:22","modified_gmt":"2022-06-07T09:40:22","slug":"la-3e-edition-du-gemab-sur-laerodrome-de-chambley","status":"publish","type":"post","link":"https:\/\/www.pilatre-de-rozier.com\/lmab\/2022\/05\/30\/la-3e-edition-du-gemab-sur-laerodrome-de-chambley\/","title":{"rendered":"La 3\u00e8 \u00e9dition du GEMAB sur l\u2019a\u00e9rodrome de Chambley"},"content":{"rendered":"\n<h3 class=\"wp-block-heading\"><strong>La 3\u00e8 \u00e9dition du GEMAB sur l\u2019a\u00e9rodrome de Chambley<\/strong><\/h3>\n\n\n\n<p>Apr\u00e8s les deux premi\u00e8res \u00e9ditions (1989 et 1991) sur l\u2019a\u00e9roport de Metz-Nancy-Lorraine, le MONDIAL AIR BALLONS qui s\u2019appelait \u00e0 l\u2019\u00e9poque la Biennale Mondiale de l\u2019A\u00e9rostation migre sur l\u2019ancienne base a\u00e9rienne am\u00e9ricaine de Chambley, \u00e0 une vingtaine de kilom\u00e8tres \u00e0 vol d\u2019oiseau. La base est d\u00e9saffect\u00e9e et sert de temps en temps \u00e0 des exercices militaires. La piste est en bon \u00e9tat, mais les 92.000 m2 de b\u00e2timents sont \u00e0 l&rsquo;abandon. Nous jetons notre d\u00e9volu sur la Tour de Contr\u00f4le qui va nous servir de PC d\u2019organisation. A l\u2019\u00e9poque, il n\u2019y a qu\u2019une entreprise de portes et de fen\u00eatres et un petit club Ulm. L\u2019eau est accessible gr\u00e2ce aux bornes \u00e0 incendie. L\u2019\u00e9lectricit\u00e9 vient des groupes \u00e9lectrog\u00e8nes que l\u2019on doit implanter. Une v\u00e9ritable sin\u00e9cure de viabiliser pour 15 jours. Il en sera ainsi jusqu\u2019en 2008, ann\u00e9e du rachat par la r\u00e9gion Lorraine. Cela fera 30 ans en 2023.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La 3\u00e8 \u00e9dition du GEMAB sur l\u2019a\u00e9rodrome de Chambley Apr\u00e8s les deux premi\u00e8res \u00e9ditions (1989 et 1991) sur l\u2019a\u00e9roport de Metz-Nancy-Lorraine, le MONDIAL AIR BALLONS qui s\u2019appelait \u00e0 l\u2019\u00e9poque la Biennale Mondiale de l\u2019A\u00e9rostation migre sur l\u2019ancienne base a\u00e9rienne am\u00e9ricaine de Chambley, \u00e0 une vingtaine de kilom\u00e8tres \u00e0 vol d\u2019oiseau. La base est d\u00e9saffect\u00e9e et [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":13829,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[1],"tags":[],"class_list":["post-13828","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actu"],"_links":{"self":[{"href":"https:\/\/www.pilatre-de-rozier.com\/lmab\/wp-json\/wp\/v2\/posts\/13828","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.pilatre-de-rozier.com\/lmab\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.pilatre-de-rozier.com\/lmab\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.pilatre-de-rozier.com\/lmab\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.pilatre-de-rozier.com\/lmab\/wp-json\/wp\/v2\/comments?post=13828"}],"version-history":[{"count":1,"href":"https:\/\/www.pilatre-de-rozier.com\/lmab\/wp-json\/wp\/v2\/posts\/13828\/revisions"}],"predecessor-version":[{"id":13830,"href":"https:\/\/www.pilatre-de-rozier.com\/lmab\/wp-json\/wp\/v2\/posts\/13828\/revisions\/13830"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.pilatre-de-rozier.com\/lmab\/wp-json\/wp\/v2\/media\/13829"}],"wp:attachment":[{"href":"https:\/\/www.pilatre-de-rozier.com\/lmab\/wp-json\/wp\/v2\/media?parent=13828"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.pilatre-de-rozier.com\/lmab\/wp-json\/wp\/v2\/categories?post=13828"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.pilatre-de-rozier.com\/lmab\/wp-json\/wp\/v2\/tags?post=13828"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}